{"id":158,"date":"2015-02-16T18:35:56","date_gmt":"2015-02-16T18:35:56","guid":{"rendered":"http:\/\/ashrae.gr\/REGISTRATION\/?page_id=158"},"modified":"2017-10-30T14:43:32","modified_gmt":"2017-10-30T14:43:32","slug":"contact-us","status":"publish","type":"page","link":"https:\/\/www.ashrae.gr\/REGISTRATION\/contact-us","title":{"rendered":"Contact Us"},"content":{"rendered":"\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1692-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1692\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/REGISTRATION\/wp-json\/wp\/v2\/pages\/158#wpcf7-f1692-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1692\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1692-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><span id=\"wpcf7-6a046ac8058aa-wrapper\" class=\"wpcf7-form-control-wrap emailsecure-1999-wrap\" style=\"display:none !important; visibility:hidden !important;\"><label for=\"wpcf7-6a046ac8058aa-field\" class=\"hp-message\">Please leave this field empty.<\/label><input id=\"wpcf7-6a046ac8058aa-field\"  class=\"wpcf7-form-control wpcf7-text\" type=\"text\" name=\"emailsecure-1999\" value=\"\" size=\"40\" tabindex=\"-1\" autocomplete=\"new-password\" \/><\/span><label> Your Name (required)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> Your Email (required)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> Subject<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span> <\/label>\n<\/p>\n<p><label> Your Message<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label><br \/>\n<br \/>\n<span class=\"wpcf7-form-control-wrap wpgdprc\"><span class=\"wpcf7-form-control wpcf7-wpgdprc wpcf7-validates-as-required\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"wpgdprc\" value=\"1\" aria-required=\"true\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">By using this form you agree with the storage and handling of your data by this website.<\/span><\/span><\/span>    <\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Send\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"49\"\/><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n\/* ]]> *\/\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width-page.php","meta":{"pmpro_default_level":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-158","page","type-page","status-publish","hentry","pmpro-has-access"],"_links":{"self":[{"href":"https:\/\/www.ashrae.gr\/REGISTRATION\/wp-json\/wp\/v2\/pages\/158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ashrae.gr\/REGISTRATION\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ashrae.gr\/REGISTRATION\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ashrae.gr\/REGISTRATION\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ashrae.gr\/REGISTRATION\/wp-json\/wp\/v2\/comments?post=158"}],"version-history":[{"count":6,"href":"https:\/\/www.ashrae.gr\/REGISTRATION\/wp-json\/wp\/v2\/pages\/158\/revisions"}],"predecessor-version":[{"id":1695,"href":"https:\/\/www.ashrae.gr\/REGISTRATION\/wp-json\/wp\/v2\/pages\/158\/revisions\/1695"}],"wp:attachment":[{"href":"https:\/\/www.ashrae.gr\/REGISTRATION\/wp-json\/wp\/v2\/media?parent=158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}